{"id":362,"date":"2017-03-06T13:56:17","date_gmt":"2017-03-06T12:56:17","guid":{"rendered":"http:\/\/www.festivals.be\/festivals-belgique\/?post_type=tribe_events&#038;p=362"},"modified":"2017-03-06T14:06:22","modified_gmt":"2017-03-06T13:06:22","slug":"frontline-2017","status":"publish","type":"tribe_events","link":"https:\/\/www.festivals.be\/festivals-belgique\/event\/frontline-2017\/","title":{"rendered":"Frontline 2017"},"content":{"rendered":"<figure id=\"attachment_359\" aria-describedby=\"caption-attachment-359\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-359\" src=\"https:\/\/i0.wp.com\/www.festivals.be\/festivals-belgique\/wp-content\/uploads\/2017\/03\/Frontline-Festival-300x300.png?resize=300%2C300\" alt=\"Frontline Festival\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.festivals.be\/festivals-belgique\/wp-content\/uploads\/2017\/03\/Frontline-Festival.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.festivals.be\/festivals-belgique\/wp-content\/uploads\/2017\/03\/Frontline-Festival.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.festivals.be\/festivals-belgique\/wp-content\/uploads\/2017\/03\/Frontline-Festival.png?w=500&amp;ssl=1 500w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><figcaption id=\"caption-attachment-359\" class=\"wp-caption-text\">Frontline Festival 2017<\/figcaption><\/figure>\n<p>Le festival electro <a href=\"http:\/\/www.festivals.be\/festivals-belgique\/festivals\/musique\/electro-et-dance\/frontline-festival\/\"><strong>Frontline<\/strong><\/a> se d\u00e9roulera cette ann\u00e9e le samedi 19 ao\u00fbt et rassemblera sur sc\u00e8nes de nombreux artistes pour vous faire danser jusqu&rsquo;au bout de la nuit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le festival electro Frontline se d\u00e9roulera cette ann\u00e9e le samedi 19 ao\u00fbt et rassemblera sur sc\u00e8nes de nombreux artistes pour vous faire danser jusqu&rsquo;au bout de la nuit.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[21,40,39,36],"tribe_events_cat":[7],"class_list":["post-362","tribe_events","type-tribe_events","status-publish","hentry","tag-21","tag-courtrai","tag-dj","tag-electro","tribe_events_cat-musique","cat_musique"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/tribe_events\/362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/comments?post=362"}],"version-history":[{"count":3,"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/tribe_events\/362\/revisions"}],"predecessor-version":[{"id":366,"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/tribe_events\/362\/revisions\/366"}],"wp:attachment":[{"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/media?parent=362"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/tags?post=362"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.festivals.be\/festivals-belgique\/wp-json\/wp\/v2\/tribe_events_cat?post=362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}